{"id":996,"date":"2021-08-10T05:35:46","date_gmt":"2021-08-10T05:35:46","guid":{"rendered":"https:\/\/jmcristobal.com\/?p=996"},"modified":"2022-02-16T23:55:55","modified_gmt":"2022-02-17T07:55:55","slug":"cisco-asa-remote-management-ssh-asdm","status":"publish","type":"post","link":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/","title":{"rendered":"Gesti\u00f3n remota de Cisco ASA - SSH\/ASDM"},"content":{"rendered":"<p>Por default la administraci\u00f3n por SSH, telnet o https est\u00e1 deshabilitada.<\/p>\n\n\n\n<p>En primer lugar debemos tener configurada la interfaz management del equipo, algo similar a:<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal# sh run interface Management0\/0\n!\ninterface Management0\/0\nmanagement-only\nnameif management\nsecurity-level 100\nip address 10.1.1.10 255.255.255.0<\/code><\/pre><\/code><\/pre>\n\n\n\n<p><strong>Habilitar SSH<\/strong><\/p>\n\n\n\n<p>Paso 1 \u2013 Configurar las llaves RSA<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# crypto key generate rsa modulus 1024\nKeypair generation process begin. Please wait\u2026<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Paso 2 \u2013 Configurar por lo menos un usuario local<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# username MyUser password MyPass privilege 15<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Paso 3 \u2013 Definir que la autenticaci\u00f3n utilice la base de datos local del ASA en sesiones SSH<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# aaa authentication ssh console LOCAL<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Paso 4 \u2013 Habilitamos SSH y permitimos las conexiones s\u00f3lo para la interfaz management desde cualquier direcci\u00f3n IP:<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# ssh 0.0.0.0 0.0.0.0 management<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Se puede definir s\u00f3lo algunos segmentos de red o hosts particulares que tengan acceso por SSH, cada segmento de red o host debe definirse en una l\u00ednea diferente. En la l\u00ednea anterior management hace referencia al nombre de la interfaz y no al tipo\/n\u00famero de la interfaz.<\/p>\n\n\n\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5583863843388929\"\n     crossorigin=\"anonymous\"><\/script>\n<!-- Cuadrado-Display-Post -->\n<ins class=\"adsbygoogle\"\n     style=\"display:block\"\n     data-ad-client=\"ca-pub-5583863843388929\"\n     data-ad-slot=\"9254203170\"\n     data-ad-format=\"auto\"\n     data-full-width-responsive=\"true\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n\n<p><strong>Habilitar administraci\u00f3n por ASDM<\/strong><\/p>\n\n\n\n<p>ASDM es el gestor GUI del ASA.<\/p>\n\n\n\n<p>Paso 1 - Validar que existe una versi\u00f3n de ASDM en el ASA<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# dir \nDirectory of disk0:\/\n805673907  -rw-  33696476     16:31:35 Nov 17 2020  asdm.bin\n1 file(s) total size: 33696476 bytes\n21475885056 bytes total (21285044224 bytes free\/99% free)<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Si el archivo no existe es necesario subir una versi\u00f3n compatible con el equipo v\u00eda FTP, SCP u otro protocolo.<\/p>\n\n\n\n<p>Paso 2 \u2013 Configurar por lo menos un usuario local<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# username MyUser password MyPass privilege 15<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Paso 3 \u2013 Definir que la autenticaci\u00f3n utilice la base de datos local del ASA en sesiones SSH<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# aaa authentication http console LOCAL<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Paso 4 - Habilitar http server<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# http server enable<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Paso 5 \u2013 Permitir conexiones http s\u00f3lo para la interfaz management desde cualquier direcci\u00f3n IP<\/p>\n\n\n\n<pre class=\"wp-block-code has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\"><pre class=\"wp-block-prismatic-blocks\"><code class=\"language-\">ASA-JMCristobal(config)# http 0.0.0.0 0.0.0.0 management<\/code><\/pre><\/code><\/pre>\n\n\n\n<p>Puede definir s\u00f3lo algunos segmentos de red o hosts particulares que tengan acceso con el ASDM, cada segmento de red o host debe ser definido en una l\u00ednea diferente. En la l\u00ednea anterior management se refiere al nombre de la interfaz y no al tipo\/n\u00famero de interfaz.<\/p>\n\n\n\n<p>Ahora s\u00f3lo queda entrar a trav\u00e9s de un navegador web a la direcci\u00f3n IP del ASA para descargar el ASDM, instalarlo y finalmente conectarse a trav\u00e9s de esta aplicaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>By default SSH, telnet or https management is disabled. First of all we must have configured the management interface of the equipment, <\/p>","protected":false},"author":2,"featured_media":1395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[243],"tags":[463,464,280,468,465,504,467,423],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cisco ASA Remote Management - SSH\/ASDM - JMCristobal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cisco ASA Remote Management - SSH\/ASDM - JMCristobal\" \/>\n<meta property=\"og:description\" content=\"By default SSH, telnet or https management is disabled. First of all we must have configured the management interface of the equipment,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\" \/>\n<meta property=\"og:site_name\" content=\"JMCristobal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/JMCristobalHomepage\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-10T05:35:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T07:55:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jmcristobal.com\/wp-content\/uploads\/2022\/01\/ASA-SSH-FeaturedPost.png\" \/>\n\t<meta property=\"og:image:width\" content=\"588\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"JMCristobal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jmcristobalhome\" \/>\n<meta name=\"twitter:site\" content=\"@jmcristobalhome\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"JMCristobal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\"},\"author\":{\"name\":\"JMCristobal\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118\"},\"headline\":\"Cisco ASA Remote Management &#8211; SSH\/ASDM\",\"datePublished\":\"2021-08-10T05:35:46+00:00\",\"dateModified\":\"2022-02-17T07:55:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\"},\"wordCount\":267,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization\"},\"keywords\":[\"asa\",\"asdm\",\"cisco\",\"firewall\",\"http\",\"management\",\"remote\",\"ssh\"],\"articleSection\":[\"Security\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\",\"url\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\",\"name\":\"Cisco ASA Remote Management - SSH\/ASDM - JMCristobal\",\"isPartOf\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website\"},\"datePublished\":\"2021-08-10T05:35:46+00:00\",\"dateModified\":\"2022-02-17T07:55:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cisco ASA Remote Management &#8211; SSH\/ASDM\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website\",\"url\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/\",\"name\":\"JMCristobal\",\"description\":\"Networking and more\",\"publisher\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization\",\"name\":\"JMCristobal\",\"url\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png\",\"contentUrl\":\"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png\",\"width\":518,\"height\":436,\"caption\":\"JMCristobal\"},\"image\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/JMCristobalHomepage\",\"https:\/\/web.facebook.com\/JMCristobalHomepage\",\"https:\/\/twitter.com\/jmcristobalhome\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118\",\"name\":\"JMCristobal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g\",\"caption\":\"JMCristobal\"},\"url\":\"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/author\/jmcristobal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cisco ASA Remote Management - SSH\/ASDM - JMCristobal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/","og_locale":"es_ES","og_type":"article","og_title":"Cisco ASA Remote Management - SSH\/ASDM - JMCristobal","og_description":"By default SSH, telnet or https management is disabled. First of all we must have configured the management interface of the equipment,","og_url":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/","og_site_name":"JMCristobal","article_publisher":"https:\/\/web.facebook.com\/JMCristobalHomepage","article_published_time":"2021-08-10T05:35:46+00:00","article_modified_time":"2022-02-17T07:55:55+00:00","og_image":[{"width":588,"height":225,"url":"https:\/\/www.jmcristobal.com\/wp-content\/uploads\/2022\/01\/ASA-SSH-FeaturedPost.png","type":"image\/png"}],"author":"JMCristobal","twitter_card":"summary_large_image","twitter_creator":"@jmcristobalhome","twitter_site":"@jmcristobalhome","twitter_misc":{"Escrito por":"JMCristobal","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#article","isPartOf":{"@id":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/"},"author":{"name":"JMCristobal","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118"},"headline":"Cisco ASA Remote Management &#8211; SSH\/ASDM","datePublished":"2021-08-10T05:35:46+00:00","dateModified":"2022-02-17T07:55:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/"},"wordCount":267,"commentCount":0,"publisher":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization"},"keywords":["asa","asdm","cisco","firewall","http","management","remote","ssh"],"articleSection":["Security"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/","url":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/","name":"Cisco ASA Remote Management - SSH\/ASDM - JMCristobal","isPartOf":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website"},"datePublished":"2021-08-10T05:35:46+00:00","dateModified":"2022-02-17T07:55:55+00:00","breadcrumb":{"@id":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jmcristobal.com\/2021\/08\/10\/cisco-asa-remote-management-ssh-asdm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cisco ASA Remote Management &#8211; SSH\/ASDM"}]},{"@type":"WebSite","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website","url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/","name":"JMCristobal","description":"Networking and more","publisher":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization","name":"JMCristobal","url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png","contentUrl":"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png","width":518,"height":436,"caption":"JMCristobal"},"image":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/JMCristobalHomepage","https:\/\/web.facebook.com\/JMCristobalHomepage","https:\/\/twitter.com\/jmcristobalhome"]},{"@type":"Person","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118","name":"JMCristobal","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g","caption":"JMCristobal"},"url":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/author\/jmcristobal\/"}]}},"jetpack_featured_media_url":"https:\/\/d1gdqjscev06po.cloudfront.net\/wp-content\/uploads\/2022\/01\/ASA-SSH-FeaturedPost.png","_links":{"self":[{"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/posts\/996"}],"collection":[{"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":11,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"predecessor-version":[{"id":1558,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/posts\/996\/revisions\/1558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/media\/1395"}],"wp:attachment":[{"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/d1gdqjscev06po.cloudfront.net\/es\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}